{"id":6,"count":5,"description":"","link":"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/","name":"Met lactose","slug":"met-lactose-gluten","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Met lactose Archieven - lolicious<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Met lactose Archieven - lolicious\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/\" \/>\n<meta property=\"og:site_name\" content=\"lolicious\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/\",\"url\":\"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/\",\"name\":\"Met lactose Archieven - lolicious\",\"isPartOf\":{\"@id\":\"https:\/\/lolicious.be\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lolicious.be\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Met lactose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lolicious.be\/#website\",\"url\":\"https:\/\/lolicious.be\/\",\"name\":\"lolicious\",\"description\":\"Delicious en gemakkelijke recepten!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lolicious.be\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Met lactose Archieven - lolicious","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/","og_locale":"nl_NL","og_type":"article","og_title":"Met lactose Archieven - lolicious","og_url":"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/","og_site_name":"lolicious","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/","url":"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/","name":"Met lactose Archieven - lolicious","isPartOf":{"@id":"https:\/\/lolicious.be\/#website"},"breadcrumb":{"@id":"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/lolicious.be\/index.php\/category\/met-lactose-gluten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lolicious.be\/"},{"@type":"ListItem","position":2,"name":"Met lactose"}]},{"@type":"WebSite","@id":"https:\/\/lolicious.be\/#website","url":"https:\/\/lolicious.be\/","name":"lolicious","description":"Delicious en gemakkelijke recepten!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lolicious.be\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/lolicious.be\/index.php\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lolicious.be\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lolicious.be\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lolicious.be\/index.php\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}